{"id":20883,"date":"2023-11-08T17:24:13","date_gmt":"2023-11-08T16:24:13","guid":{"rendered":"https:\/\/gimperamodels.com\/?post_type=modelo&#038;p=20883"},"modified":"2024-07-25T17:26:05","modified_gmt":"2024-07-25T15:26:05","slug":"pol-meliz","status":"publish","type":"modelo","link":"https:\/\/gimperamodels.com\/en\/modelo\/pol-meliz\/","title":{"rendered":"POL MELIZ"},"featured_media":22842,"template":"","categoria_modelo":[174],"columnas_galeria":[],"class_list":["post-20883","modelo","type-modelo","status-publish","has-post-thumbnail","hentry","categoria_modelo-comercial-ninos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>POL MELIZ | Gimpera Models | Agencia de Modelos en Barcelona<\/title>\n<meta name=\"description\" content=\"Agencia de modelos y actores ubicada en Barcelona. MODEL AGENCY BCN\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"POL MELIZ | Gimpera Models | Agencia de Modelos en Barcelona\" \/>\n<meta property=\"og:description\" content=\"Agencia de modelos y actores ubicada en Barcelona. MODEL AGENCY BCN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimperamodels.com\/en\/modelo\/pol-meliz\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimpera Models | Agencia de Modelos en Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gimpera\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-25T15:26:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimperamodels.com\/wp-content\/uploads\/2023\/11\/POL-MELIZ-D.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/pol-meliz\\\/\",\"url\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/pol-meliz\\\/\",\"name\":\"POL MELIZ | Gimpera Models | Agencia de Modelos en Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/pol-meliz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/pol-meliz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimperamodels.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/POL-MELIZ-D.jpg\",\"datePublished\":\"2023-11-08T16:24:13+00:00\",\"dateModified\":\"2024-07-25T15:26:05+00:00\",\"description\":\"Agencia de modelos y actores ubicada en Barcelona. MODEL AGENCY BCN\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/pol-meliz\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/pol-meliz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/pol-meliz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimperamodels.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/POL-MELIZ-D.jpg\",\"contentUrl\":\"https:\\\/\\\/gimperamodels.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/POL-MELIZ-D.jpg\",\"width\":600,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/pol-meliz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gimperamodels.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"POL MELIZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/\",\"name\":\"Gimpera Models | Agencia de modelos en Barcelona\",\"description\":\"Agencia de Modelos y Actores en Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/#organization\"},\"alternateName\":\"Gimpera Models BCN\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/#organization\",\"name\":\"Gimpera Models | Agencia de modelos en Barcelona\",\"alternateName\":\"Gimpera Models\",\"url\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimperamodels.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/gimperamodels.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo-2.png\",\"width\":1183,\"height\":211,\"caption\":\"Gimpera Models | Agencia de modelos en Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gimpera\",\"https:\\\/\\\/www.instagram.com\\\/gimperamodels\\\/?hl=es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"POL MELIZ | Gimpera Models | Agencia de Modelos en Barcelona","description":"Agencia de modelos y actores ubicada en Barcelona. MODEL AGENCY BCN","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"POL MELIZ | Gimpera Models | Agencia de Modelos en Barcelona","og_description":"Agencia de modelos y actores ubicada en Barcelona. MODEL AGENCY BCN","og_url":"https:\/\/gimperamodels.com\/en\/modelo\/pol-meliz\/","og_site_name":"Gimpera Models | Agencia de Modelos en Barcelona","article_publisher":"https:\/\/www.facebook.com\/gimpera","article_modified_time":"2024-07-25T15:26:05+00:00","og_image":[{"width":600,"height":700,"url":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2023\/11\/POL-MELIZ-D.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gimperamodels.com\/modelo\/pol-meliz\/","url":"https:\/\/gimperamodels.com\/modelo\/pol-meliz\/","name":"POL MELIZ | Gimpera Models | Agencia de Modelos en Barcelona","isPartOf":{"@id":"https:\/\/gimperamodels.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimperamodels.com\/modelo\/pol-meliz\/#primaryimage"},"image":{"@id":"https:\/\/gimperamodels.com\/modelo\/pol-meliz\/#primaryimage"},"thumbnailUrl":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2023\/11\/POL-MELIZ-D.jpg","datePublished":"2023-11-08T16:24:13+00:00","dateModified":"2024-07-25T15:26:05+00:00","description":"Agencia de modelos y actores ubicada en Barcelona. MODEL AGENCY BCN","breadcrumb":{"@id":"https:\/\/gimperamodels.com\/modelo\/pol-meliz\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimperamodels.com\/modelo\/pol-meliz\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gimperamodels.com\/modelo\/pol-meliz\/#primaryimage","url":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2023\/11\/POL-MELIZ-D.jpg","contentUrl":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2023\/11\/POL-MELIZ-D.jpg","width":600,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/gimperamodels.com\/modelo\/pol-meliz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gimperamodels.com\/"},{"@type":"ListItem","position":2,"name":"POL MELIZ"}]},{"@type":"WebSite","@id":"https:\/\/gimperamodels.com\/en\/#website","url":"https:\/\/gimperamodels.com\/en\/","name":"Gimpera Models | Agencia de modelos en Barcelona","description":"Agencia de Modelos y Actores en Barcelona","publisher":{"@id":"https:\/\/gimperamodels.com\/en\/#organization"},"alternateName":"Gimpera Models BCN","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimperamodels.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gimperamodels.com\/en\/#organization","name":"Gimpera Models | Agencia de modelos en Barcelona","alternateName":"Gimpera Models","url":"https:\/\/gimperamodels.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gimperamodels.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2023\/11\/logo-2.png","contentUrl":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2023\/11\/logo-2.png","width":1183,"height":211,"caption":"Gimpera Models | Agencia de modelos en Barcelona"},"image":{"@id":"https:\/\/gimperamodels.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gimpera","https:\/\/www.instagram.com\/gimperamodels\/?hl=es"]}]}},"galeria_":[{"ID":"22840","post_author":"2","post_date":"2024-02-20 12:09:23","post_date_gmt":"2024-02-20 11:09:23","post_content":"","post_title":"POL MELIZ 1","post_excerpt":"","post_status":"inherit","comment_status":"open","ping_status":"closed","post_password":"","post_name":"pol-meliz-1","to_ping":"","pinged":"","post_modified":"2024-02-20 12:09:23","post_modified_gmt":"2024-02-20 11:09:23","post_content_filtered":"","post_parent":"20883","guid":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2023\/11\/POL-MELIZ-1.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"22840"},{"ID":"22841","post_author":"2","post_date":"2024-02-20 12:09:34","post_date_gmt":"2024-02-20 11:09:34","post_content":"","post_title":"POL MELIZ 2","post_excerpt":"","post_status":"inherit","comment_status":"open","ping_status":"closed","post_password":"","post_name":"pol-meliz-2","to_ping":"","pinged":"","post_modified":"2024-02-20 12:09:34","post_modified_gmt":"2024-02-20 11:09:34","post_content_filtered":"","post_parent":"20883","guid":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2023\/11\/POL-MELIZ-2.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"22841"}],"_links":{"self":[{"href":"https:\/\/gimperamodels.com\/en\/wp-json\/wp\/v2\/modelo\/20883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimperamodels.com\/en\/wp-json\/wp\/v2\/modelo"}],"about":[{"href":"https:\/\/gimperamodels.com\/en\/wp-json\/wp\/v2\/types\/modelo"}],"version-history":[{"count":0,"href":"https:\/\/gimperamodels.com\/en\/wp-json\/wp\/v2\/modelo\/20883\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimperamodels.com\/en\/wp-json\/wp\/v2\/media\/22842"}],"wp:attachment":[{"href":"https:\/\/gimperamodels.com\/en\/wp-json\/wp\/v2\/media?parent=20883"}],"wp:term":[{"taxonomy":"categoria_modelo","embeddable":true,"href":"https:\/\/gimperamodels.com\/en\/wp-json\/wp\/v2\/categoria_modelo?post=20883"},{"taxonomy":"columnas_galeria","embeddable":true,"href":"https:\/\/gimperamodels.com\/en\/wp-json\/wp\/v2\/columnas_galeria?post=20883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}