{"id":20713,"date":"2023-11-07T19:15:27","date_gmt":"2023-11-07T18:15:27","guid":{"rendered":"https:\/\/gimperamodels.com\/?post_type=modelo&#038;p=20713"},"modified":"2024-07-25T16:58:41","modified_gmt":"2024-07-25T14:58:41","slug":"victor-moya","status":"publish","type":"modelo","link":"https:\/\/gimperamodels.com\/ca\/modelo\/victor-moya\/","title":{"rendered":"V\u00cdCTOR MOYA"},"featured_media":19814,"template":"","categoria_modelo":[172],"columnas_galeria":[],"class_list":["post-20713","modelo","type-modelo","status-publish","has-post-thumbnail","hentry","categoria_modelo-comercial-hombres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V\u00cdCTOR MOYA | Gimpera Models | Agencia de Modelos en Barcelona<\/title>\n<meta name=\"description\" content=\"Agencia de modelos y actores ubicada en Barcelona. MODEL AGENCY BCN\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u00cdCTOR MOYA | Gimpera Models | Agencia de Modelos en Barcelona\" \/>\n<meta property=\"og:description\" content=\"Agencia de modelos y actores ubicada en Barcelona. MODEL AGENCY BCN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimperamodels.com\/ca\/modelo\/victor-moya\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimpera Models | Agencia de Modelos en Barcelona\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gimpera\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-25T14:58:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimperamodels.com\/wp-content\/uploads\/2021\/10\/VIC-MOYA-TG-D.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/victor-moya\\\/\",\"url\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/victor-moya\\\/\",\"name\":\"V\u00cdCTOR MOYA | Gimpera Models | Agencia de Modelos en Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/victor-moya\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/victor-moya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimperamodels.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/VIC-MOYA-TG-D.jpg\",\"datePublished\":\"2023-11-07T18:15:27+00:00\",\"dateModified\":\"2024-07-25T14:58:41+00:00\",\"description\":\"Agencia de modelos y actores ubicada en Barcelona. MODEL AGENCY BCN\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/victor-moya\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/victor-moya\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/victor-moya\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimperamodels.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/VIC-MOYA-TG-D.jpg\",\"contentUrl\":\"https:\\\/\\\/gimperamodels.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/VIC-MOYA-TG-D.jpg\",\"width\":600,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/modelo\\\/victor-moya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gimperamodels.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00cdCTOR MOYA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/\",\"name\":\"Gimpera Models | Agencia de modelos en Barcelona\",\"description\":\"Agencia de Modelos y Actores en Barcelona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/#organization\"},\"alternateName\":\"Gimpera Models BCN\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/#organization\",\"name\":\"Gimpera Models | Agencia de modelos en Barcelona\",\"alternateName\":\"Gimpera Models\",\"url\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimperamodels.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo-2.png\",\"contentUrl\":\"https:\\\/\\\/gimperamodels.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/logo-2.png\",\"width\":1183,\"height\":211,\"caption\":\"Gimpera Models | Agencia de modelos en Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/gimperamodels.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gimpera\",\"https:\\\/\\\/www.instagram.com\\\/gimperamodels\\\/?hl=es\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u00cdCTOR MOYA | Gimpera Models | Agencia de Modelos en Barcelona","description":"Agencia de modelos y actores ubicada en Barcelona. MODEL AGENCY BCN","robots":{"index":"noindex","follow":"follow"},"og_locale":"ca_ES","og_type":"article","og_title":"V\u00cdCTOR MOYA | Gimpera Models | Agencia de Modelos en Barcelona","og_description":"Agencia de modelos y actores ubicada en Barcelona. MODEL AGENCY BCN","og_url":"https:\/\/gimperamodels.com\/ca\/modelo\/victor-moya\/","og_site_name":"Gimpera Models | Agencia de Modelos en Barcelona","article_publisher":"https:\/\/www.facebook.com\/gimpera","article_modified_time":"2024-07-25T14:58:41+00:00","og_image":[{"width":600,"height":700,"url":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2021\/10\/VIC-MOYA-TG-D.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gimperamodels.com\/modelo\/victor-moya\/","url":"https:\/\/gimperamodels.com\/modelo\/victor-moya\/","name":"V\u00cdCTOR MOYA | Gimpera Models | Agencia de Modelos en Barcelona","isPartOf":{"@id":"https:\/\/gimperamodels.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimperamodels.com\/modelo\/victor-moya\/#primaryimage"},"image":{"@id":"https:\/\/gimperamodels.com\/modelo\/victor-moya\/#primaryimage"},"thumbnailUrl":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2021\/10\/VIC-MOYA-TG-D.jpg","datePublished":"2023-11-07T18:15:27+00:00","dateModified":"2024-07-25T14:58:41+00:00","description":"Agencia de modelos y actores ubicada en Barcelona. MODEL AGENCY BCN","breadcrumb":{"@id":"https:\/\/gimperamodels.com\/modelo\/victor-moya\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimperamodels.com\/modelo\/victor-moya\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/gimperamodels.com\/modelo\/victor-moya\/#primaryimage","url":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2021\/10\/VIC-MOYA-TG-D.jpg","contentUrl":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2021\/10\/VIC-MOYA-TG-D.jpg","width":600,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/gimperamodels.com\/modelo\/victor-moya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gimperamodels.com\/"},{"@type":"ListItem","position":2,"name":"V\u00cdCTOR MOYA"}]},{"@type":"WebSite","@id":"https:\/\/gimperamodels.com\/en\/#website","url":"https:\/\/gimperamodels.com\/en\/","name":"Gimpera Models | Agencia de modelos en Barcelona","description":"Agencia de Modelos y Actores en Barcelona","publisher":{"@id":"https:\/\/gimperamodels.com\/en\/#organization"},"alternateName":"Gimpera Models BCN","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimperamodels.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/gimperamodels.com\/en\/#organization","name":"Gimpera Models | Agencia de modelos en Barcelona","alternateName":"Gimpera Models","url":"https:\/\/gimperamodels.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/gimperamodels.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2023\/11\/logo-2.png","contentUrl":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2023\/11\/logo-2.png","width":1183,"height":211,"caption":"Gimpera Models | Agencia de modelos en Barcelona"},"image":{"@id":"https:\/\/gimperamodels.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gimpera","https:\/\/www.instagram.com\/gimperamodels\/?hl=es"]}]}},"galeria_":[{"ID":"19812","post_author":"2","post_date":"2021-10-07 16:16:06","post_date_gmt":"2021-10-07 14:16:06","post_content":"","post_title":"VIC MOYA - TG (34)","post_excerpt":"","post_status":"inherit","comment_status":"open","ping_status":"closed","post_password":"","post_name":"vic-moya-tg-34","to_ping":"","pinged":"","post_modified":"2021-10-07 16:16:06","post_modified_gmt":"2021-10-07 14:16:06","post_content_filtered":"","post_parent":"19809","guid":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2021\/10\/VIC-MOYA-TG-34.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"19812"},{"ID":"19813","post_author":"2","post_date":"2021-10-07 16:16:09","post_date_gmt":"2021-10-07 14:16:09","post_content":"","post_title":"VIC MOYA - TG (81)","post_excerpt":"","post_status":"inherit","comment_status":"open","ping_status":"closed","post_password":"","post_name":"vic-moya-tg-81","to_ping":"","pinged":"","post_modified":"2021-10-07 16:16:09","post_modified_gmt":"2021-10-07 14:16:09","post_content_filtered":"","post_parent":"19809","guid":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2021\/10\/VIC-MOYA-TG-81.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"19813"},{"ID":"19811","post_author":"2","post_date":"2021-10-07 16:16:02","post_date_gmt":"2021-10-07 14:16:02","post_content":"","post_title":"VIC MOYA - TG (17)","post_excerpt":"","post_status":"inherit","comment_status":"open","ping_status":"closed","post_password":"","post_name":"vic-moya-tg-17","to_ping":"","pinged":"","post_modified":"2021-10-07 16:16:02","post_modified_gmt":"2021-10-07 14:16:02","post_content_filtered":"","post_parent":"19809","guid":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2021\/10\/VIC-MOYA-TG-17.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"19811"},{"ID":"19810","post_author":"2","post_date":"2021-10-07 16:15:59","post_date_gmt":"2021-10-07 14:15:59","post_content":"","post_title":"VIC MOYA - TG (1)","post_excerpt":"","post_status":"inherit","comment_status":"open","ping_status":"closed","post_password":"","post_name":"vic-moya-tg-1","to_ping":"","pinged":"","post_modified":"2021-10-07 16:15:59","post_modified_gmt":"2021-10-07 14:15:59","post_content_filtered":"","post_parent":"19809","guid":"https:\/\/gimperamodels.com\/wp-content\/uploads\/2021\/10\/VIC-MOYA-TG-1.jpg","menu_order":"0","post_type":"attachment","post_mime_type":"image\/jpeg","comment_count":"0","pod_item_id":"19810"}],"_links":{"self":[{"href":"https:\/\/gimperamodels.com\/ca\/wp-json\/wp\/v2\/modelo\/20713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimperamodels.com\/ca\/wp-json\/wp\/v2\/modelo"}],"about":[{"href":"https:\/\/gimperamodels.com\/ca\/wp-json\/wp\/v2\/types\/modelo"}],"version-history":[{"count":0,"href":"https:\/\/gimperamodels.com\/ca\/wp-json\/wp\/v2\/modelo\/20713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimperamodels.com\/ca\/wp-json\/wp\/v2\/media\/19814"}],"wp:attachment":[{"href":"https:\/\/gimperamodels.com\/ca\/wp-json\/wp\/v2\/media?parent=20713"}],"wp:term":[{"taxonomy":"categoria_modelo","embeddable":true,"href":"https:\/\/gimperamodels.com\/ca\/wp-json\/wp\/v2\/categoria_modelo?post=20713"},{"taxonomy":"columnas_galeria","embeddable":true,"href":"https:\/\/gimperamodels.com\/ca\/wp-json\/wp\/v2\/columnas_galeria?post=20713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}